{"id":71979,"date":"2023-03-17T11:47:30","date_gmt":"2023-03-17T10:47:30","guid":{"rendered":"https:\/\/test.sollux-lighting.com\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/"},"modified":"2024-03-26T16:59:41","modified_gmt":"2024-03-26T15:59:41","slug":"lampada-da-soffitto-massimo-bianco","status":"publish","type":"product","link":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/","title":{"rendered":"Lampada da soffitto MASSIMO bianco"},"content":{"rendered":"<p>Massimo \u00e8 una collezione di lampade moderne da soffitto e da parete. Sono ideali per gli ambienti in cui si desidera un&#8217;illuminazione piuttosto leggera e leggermente fumosa. Sia gli interni scandinavi che quelli ultramoderni trarranno beneficio dalle lampade Massimo. Le lampade Massimo hanno pi\u00f9 di una destinazione: si adattano bene alla cucina, al corridoio e persino alla camera da letto. Il pannello cromato \u00e8 un dettaglio interessante che fa risaltare queste lampade moderne rispetto alle altre collezioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bulbola lampadina: E27, 2x60W, LED 2x15W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I<br \/>\nLampadina non inclusa.<br \/>\nDimensioni: 65\/50\/11 cm<br \/>\nMateriale: acciaio, vetro<br \/>\nColore bianco<\/p>\n","protected":false},"featured_media":57544,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-71979","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lampada da soffitto MASSIMO bianco - Sollux Lighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampada da soffitto MASSIMO bianco - Sollux Lighting\" \/>\n<meta property=\"og:description\" content=\"Bulbola lampadina: E27, 2x60W, LED 2x15W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 65\/50\/11 cm Materiale: acciaio, vetro Colore bianco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/\" \/>\n<meta property=\"og:site_name\" content=\"Sollux Lighting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T15:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/\",\"url\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/\",\"name\":\"Lampada da soffitto MASSIMO bianco - Sollux Lighting\",\"isPartOf\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg\",\"datePublished\":\"2023-03-17T10:47:30+00:00\",\"dateModified\":\"2024-03-26T15:59:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principale\",\"item\":\"https:\/\/sollux-lighting.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra offerta\",\"item\":\"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampada da soffitto MASSIMO bianco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"name\":\"Sollux Lighting\",\"description\":\"Brighten up your business\",\"publisher\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\",\"name\":\"Sollux Lighting\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"width\":160,\"height\":46,\"caption\":\"Sollux Lighting \"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampada da soffitto MASSIMO bianco - Sollux Lighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/","og_locale":"it_IT","og_type":"article","og_title":"Lampada da soffitto MASSIMO bianco - Sollux Lighting","og_description":"Bulbola lampadina: E27, 2x60W, LED 2x15W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 65\/50\/11 cm Materiale: acciaio, vetro Colore bianco","og_url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/","og_site_name":"Sollux Lighting","article_modified_time":"2024-03-26T15:59:41+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/","url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/","name":"Lampada da soffitto MASSIMO bianco - Sollux Lighting","isPartOf":{"@id":"https:\/\/sollux-lighting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage"},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage"},"thumbnailUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg","datePublished":"2023-03-17T10:47:30+00:00","dateModified":"2024-03-26T15:59:41+00:00","breadcrumb":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#primaryimage","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/1045-1-k.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-massimo-bianco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principale","item":"https:\/\/sollux-lighting.com\/it\/"},{"@type":"ListItem","position":2,"name":"La nostra offerta","item":"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/"},{"@type":"ListItem","position":3,"name":"Lampada da soffitto MASSIMO bianco"}]},{"@type":"WebSite","@id":"https:\/\/sollux-lighting.com\/it\/#website","url":"https:\/\/sollux-lighting.com\/it\/","name":"Sollux Lighting","description":"Brighten up your business","publisher":{"@id":"https:\/\/sollux-lighting.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sollux-lighting.com\/it\/#organization","name":"Sollux Lighting","url":"https:\/\/sollux-lighting.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","width":160,"height":46,"caption":"Sollux Lighting "},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product\/71979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media\/57544"}],"wp:attachment":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media?parent=71979"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_brand?post=71979"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_cat?post=71979"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_tag?post=71979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}