{"id":71578,"date":"2023-03-17T11:23:33","date_gmt":"2023-03-17T10:23:33","guid":{"rendered":"https:\/\/test.sollux-lighting.com\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/"},"modified":"2024-03-26T16:12:40","modified_gmt":"2024-03-26T15:12:40","slug":"lampada-da-soffitto-quad-in-legno-naturale","status":"publish","type":"product","link":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/","title":{"rendered":"Lampada da soffitto QUAD in legno naturale"},"content":{"rendered":"<p>Questa elegante lampada ha molti vantaggi e grazie a questo nessun appassionato di design scandinavo rimarr\u00e0 indifferente. Si tratta di un modello realizzato in legno, per il quale l&#8217;ispirazione principale \u00e8 stata un solido geometrico a forma di cubo. La tonalit\u00e0 naturale del materiale utilizzato si adatta bene a diverse disposizioni &#8211; contrariamente alle apparenze, questa non \u00e8 un&#8217;offerta dedicata esclusivamente agli interni scandinavi. \u00c8 possibile integrare facilmente la lampada in un soggiorno arredato in stile classico o in una stanza in cui dominano le tendenze moderniste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bulbola lampadina: GU10, 1x40W, LED 1x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I<br \/>\nLampadina non inclusa.<br \/>\nDimensioni: 10\/10\/10 cm<br \/>\nMateriale: legno<br \/>\nColore: legno naturale<\/p>\n","protected":false},"featured_media":47503,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-71578","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lampada da soffitto QUAD in legno naturale - Sollux Lighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampada da soffitto QUAD in legno naturale - Sollux Lighting\" \/>\n<meta property=\"og:description\" content=\"Bulbola lampadina: GU10, 1x40W, LED 1x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 10\/10\/10 cm Materiale: legno Colore: legno naturale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/\" \/>\n<meta property=\"og:site_name\" content=\"Sollux Lighting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T15:12:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/\",\"url\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/\",\"name\":\"Lampada da soffitto QUAD in legno naturale - Sollux Lighting\",\"isPartOf\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg\",\"datePublished\":\"2023-03-17T10:23:33+00:00\",\"dateModified\":\"2024-03-26T15:12:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principale\",\"item\":\"https:\/\/sollux-lighting.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra offerta\",\"item\":\"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampada da soffitto QUAD in legno naturale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"name\":\"Sollux Lighting\",\"description\":\"Brighten up your business\",\"publisher\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\",\"name\":\"Sollux Lighting\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"width\":160,\"height\":46,\"caption\":\"Sollux Lighting \"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampada da soffitto QUAD in legno naturale - Sollux Lighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/","og_locale":"it_IT","og_type":"article","og_title":"Lampada da soffitto QUAD in legno naturale - Sollux Lighting","og_description":"Bulbola lampadina: GU10, 1x40W, LED 1x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 10\/10\/10 cm Materiale: legno Colore: legno naturale","og_url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/","og_site_name":"Sollux Lighting","article_modified_time":"2024-03-26T15:12:40+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/","url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/","name":"Lampada da soffitto QUAD in legno naturale - Sollux Lighting","isPartOf":{"@id":"https:\/\/sollux-lighting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage"},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg","datePublished":"2023-03-17T10:23:33+00:00","dateModified":"2024-03-26T15:12:40+00:00","breadcrumb":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#primaryimage","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0493-1-k.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-soffitto-quad-in-legno-naturale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principale","item":"https:\/\/sollux-lighting.com\/it\/"},{"@type":"ListItem","position":2,"name":"La nostra offerta","item":"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/"},{"@type":"ListItem","position":3,"name":"Lampada da soffitto QUAD in legno naturale"}]},{"@type":"WebSite","@id":"https:\/\/sollux-lighting.com\/it\/#website","url":"https:\/\/sollux-lighting.com\/it\/","name":"Sollux Lighting","description":"Brighten up your business","publisher":{"@id":"https:\/\/sollux-lighting.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sollux-lighting.com\/it\/#organization","name":"Sollux Lighting","url":"https:\/\/sollux-lighting.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","width":160,"height":46,"caption":"Sollux Lighting "},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product\/71578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media\/47503"}],"wp:attachment":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media?parent=71578"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_brand?post=71578"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_cat?post=71578"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_tag?post=71578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}