{"id":71528,"date":"2023-03-17T11:21:21","date_gmt":"2023-03-17T10:21:21","guid":{"rendered":"https:\/\/test.sollux-lighting.com\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/"},"modified":"2024-03-26T16:08:18","modified_gmt":"2024-03-26T15:08:18","slug":"lampada-da-parete-tre-nera","status":"publish","type":"product","link":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/","title":{"rendered":"Lampada da parete TRE nera"},"content":{"rendered":"<p>Questa lampada insolita presenta un design modernistico. La applique si adatta perfettamente agli interni mantenuti in uno stile moderno, tra cui gli allestimenti scandinavi o loft. \u00c8 stata realizzata in acciaio, motivo per cui la sua ottima durata \u00e8 un ulteriore punto di forza. L&#8217;attenzione \u00e8 principalmente attratta dalla sua forma decorativa, grazie alla quale la lampada pu\u00f2 essere una decorazione originale del soggiorno, della camera da letto o del corridoio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bulbola lampadina: G9, 2x40W, LED 2x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I<br \/>\nLampadina non inclusa.<br \/>\nDimensioni: 30\/30\/8 cm<br \/>\nMateriale: acciaio<br \/>\nColore nero<\/p>\n","protected":false},"featured_media":46312,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-71528","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lampada da parete TRE nera - Sollux Lighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampada da parete TRE nera - Sollux Lighting\" \/>\n<meta property=\"og:description\" content=\"Bulbola lampadina: G9, 2x40W, LED 2x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 30\/30\/8 cm Materiale: acciaio Colore nero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/\" \/>\n<meta property=\"og:site_name\" content=\"Sollux Lighting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T15:08:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/\",\"url\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/\",\"name\":\"Lampada da parete TRE nera - Sollux Lighting\",\"isPartOf\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg\",\"datePublished\":\"2023-03-17T10:21:21+00:00\",\"dateModified\":\"2024-03-26T15:08:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principale\",\"item\":\"https:\/\/sollux-lighting.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra offerta\",\"item\":\"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampada da parete TRE nera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#website\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"name\":\"Sollux Lighting\",\"description\":\"Brighten up your business\",\"publisher\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#organization\",\"name\":\"Sollux Lighting\",\"url\":\"https:\/\/sollux-lighting.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"width\":160,\"height\":46,\"caption\":\"Sollux Lighting \"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampada da parete TRE nera - Sollux Lighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/","og_locale":"it_IT","og_type":"article","og_title":"Lampada da parete TRE nera - Sollux Lighting","og_description":"Bulbola lampadina: G9, 2x40W, LED 2x12W, 50-60Hz, ~ 220-230V, IP20, Classe di elettrodomestici I Lampadina non inclusa. Dimensioni: 30\/30\/8 cm Materiale: acciaio Colore nero","og_url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/","og_site_name":"Sollux Lighting","article_modified_time":"2024-03-26T15:08:18+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/","url":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/","name":"Lampada da parete TRE nera - Sollux Lighting","isPartOf":{"@id":"https:\/\/sollux-lighting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage"},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage"},"thumbnailUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg","datePublished":"2023-03-17T10:21:21+00:00","dateModified":"2024-03-26T15:08:18+00:00","breadcrumb":{"@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#primaryimage","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/0425-1-k.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/sollux-lighting.com\/it\/nasza-oferta\/senza-categoria\/lampada-da-parete-tre-nera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principale","item":"https:\/\/sollux-lighting.com\/it\/"},{"@type":"ListItem","position":2,"name":"La nostra offerta","item":"https:\/\/sollux-lighting.com\/it\/la-nostra-offerta\/"},{"@type":"ListItem","position":3,"name":"Lampada da parete TRE nera"}]},{"@type":"WebSite","@id":"https:\/\/sollux-lighting.com\/it\/#website","url":"https:\/\/sollux-lighting.com\/it\/","name":"Sollux Lighting","description":"Brighten up your business","publisher":{"@id":"https:\/\/sollux-lighting.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sollux-lighting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sollux-lighting.com\/it\/#organization","name":"Sollux Lighting","url":"https:\/\/sollux-lighting.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","width":160,"height":46,"caption":"Sollux Lighting "},"image":{"@id":"https:\/\/sollux-lighting.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product\/71528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media\/46312"}],"wp:attachment":[{"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/media?parent=71528"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_brand?post=71528"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_cat?post=71528"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sollux-lighting.com\/it\/wp-json\/wp\/v2\/product_tag?post=71528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}