{"id":74685,"date":"2024-03-26T17:47:21","date_gmt":"2024-03-26T16:47:21","guid":{"rendered":"https:\/\/test.sollux-lighting.com\/nasza-oferta\/sin%20categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/"},"modified":"2024-03-26T22:23:38","modified_gmt":"2024-03-26T21:23:38","slug":"lampadario-rio-3-55-78-110-bianco-led-4000k","status":"publish","type":"product","link":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/","title":{"rendered":"Lampadario RIO 3 55\/78\/110 bianco LED 4000K"},"content":{"rendered":"<p>RIO impresiona con su versatilidad. Una l\u00e1mpara de ara\u00f1a (simple, doble o triple) y una l\u00e1mpara de techo son su versi\u00f3n regular. Una variaci\u00f3n art\u00edstica en el tema RIO es la l\u00e1mpara colgante vertical, que ofrece infinitas posibilidades de disposici\u00f3n tanto en privado como en el pasillo, sala de estar, vestidor, ba\u00f1o, as\u00ed como en elegantes espacios p\u00fablicos como: centro de bienestar, sal\u00f3n de SPA, galer\u00eda, boutique, restaurante, oficina. Los c\u00edrculos LED minimalistas modernos garantizan una alta est\u00e9tica y par\u00e1metros de iluminaci\u00f3n (3000K CRI 90, 4000K CRI 95) Lumens altos combinados con una fuente de luz LED). La apariencia est\u00e9tica de la luminaria tambi\u00e9n garantiza las dimensiones del perfil: altura 40 mm, ancho 8 mm. Al igual que todas nuestras l\u00e1mparas, los anillos se producen \u00edntegramente en Polonia. Por eso podemos garantizar a nuestros clientes un tiempo de finalizaci\u00f3n de pedido r\u00e1pido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente de luz: LED, 100W, 12073lm, 4000K, CRI98, 50Hz, ~230V, IP20, clase de protecci\u00f3n I<br \/>\nLa fuente de luz est\u00e1 incluida.<br \/>\nDimensiones: 110\/110\/150 cm<br \/>\nAltura del perfil: 4 cm<br \/>\nAncho del perfil: 0,8 cm<br \/>\nMaterial: aluminio<br \/>\nColor: blanco<\/p>\n","protected":false},"featured_media":38201,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-74685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin%20categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting\" \/>\n<meta property=\"og:description\" content=\"Fuente de luz: LED, 100W, 12073lm, 4000K, CRI98, 50Hz, ~230V, IP20, clase de protecci\u00f3n I La fuente de luz est\u00e1 incluida. Dimensiones: 110\/110\/150 cm Altura del perfil: 4 cm Ancho del perfil: 0,8 cm Material: aluminio Color: blanco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/\" \/>\n<meta property=\"og:site_name\" content=\"Sollux Lighting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T21:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/\",\"url\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/\",\"name\":\"Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting\",\"isPartOf\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg\",\"datePublished\":\"2024-03-26T16:47:21+00:00\",\"dateModified\":\"2024-03-26T21:23:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina principal\",\"item\":\"https:\/\/sollux-lighting.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestra oferta\",\"item\":\"https:\/\/sollux-lighting.com\/es\/nuestra-oferta\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampadario RIO 3 55\/78\/110 bianco LED 4000K\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/#website\",\"url\":\"https:\/\/sollux-lighting.com\/es\/\",\"name\":\"Sollux Lighting\",\"description\":\"Brighten up your business\",\"publisher\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sollux-lighting.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/#organization\",\"name\":\"Sollux Lighting\",\"url\":\"https:\/\/sollux-lighting.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sollux-lighting.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"contentUrl\":\"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg\",\"width\":160,\"height\":46,\"caption\":\"Sollux Lighting \"},\"image\":{\"@id\":\"https:\/\/sollux-lighting.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/","og_locale":"es_ES","og_type":"article","og_title":"Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting","og_description":"Fuente de luz: LED, 100W, 12073lm, 4000K, CRI98, 50Hz, ~230V, IP20, clase de protecci\u00f3n I La fuente de luz est\u00e1 incluida. Dimensiones: 110\/110\/150 cm Altura del perfil: 4 cm Ancho del perfil: 0,8 cm Material: aluminio Color: blanco","og_url":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/","og_site_name":"Sollux Lighting","article_modified_time":"2024-03-26T21:23:38+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/","url":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/","name":"Lampadario RIO 3 55\/78\/110 bianco LED 4000K - Sollux Lighting","isPartOf":{"@id":"https:\/\/sollux-lighting.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage"},"image":{"@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage"},"thumbnailUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg","datePublished":"2024-03-26T16:47:21+00:00","dateModified":"2024-03-26T21:23:38+00:00","breadcrumb":{"@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#primaryimage","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/03\/271-1-k.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/sollux-lighting.com\/es\/nasza-oferta\/sin categor\u00eda\/lampadario-rio-3-55-78-110-bianco-led-4000k\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina principal","item":"https:\/\/sollux-lighting.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nuestra oferta","item":"https:\/\/sollux-lighting.com\/es\/nuestra-oferta\/"},{"@type":"ListItem","position":3,"name":"Lampadario RIO 3 55\/78\/110 bianco LED 4000K"}]},{"@type":"WebSite","@id":"https:\/\/sollux-lighting.com\/es\/#website","url":"https:\/\/sollux-lighting.com\/es\/","name":"Sollux Lighting","description":"Brighten up your business","publisher":{"@id":"https:\/\/sollux-lighting.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sollux-lighting.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sollux-lighting.com\/es\/#organization","name":"Sollux Lighting","url":"https:\/\/sollux-lighting.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sollux-lighting.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","contentUrl":"https:\/\/sollux-lighting.com\/wp-content\/uploads\/2023\/02\/LOGO.svg","width":160,"height":46,"caption":"Sollux Lighting "},"image":{"@id":"https:\/\/sollux-lighting.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/product\/74685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/media\/38201"}],"wp:attachment":[{"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/media?parent=74685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/product_brand?post=74685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/product_cat?post=74685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sollux-lighting.com\/es\/wp-json\/wp\/v2\/product_tag?post=74685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}